{"id":3484,"date":"2023-07-31T11:10:38","date_gmt":"2023-07-31T09:10:38","guid":{"rendered":"https:\/\/filmotecacantabria.es\/es\/?p=3484"},"modified":"2023-07-31T11:10:38","modified_gmt":"2023-07-31T09:10:38","slug":"iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros","status":"publish","type":"post","link":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/","title":{"rendered":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros."},"content":{"rendered":"<p><strong>El mes que viene contin\u00faan los ciclos \u2018Fuera de foco. Premiadas\u2019, \u2018Por amor al cine\u2019 y \u2018S\u00e8rie noire\u2019, junto a las habituales proyecciones de t\u00edtulos in\u00e9ditos y para p\u00fablico familiar<\/strong><\/p>\n<p><strong>Santander, 31 de julio de 2023.- <\/strong>La Filmoteca de Cantabria Mario Camus inicia en agosto un ciclo especial dedicado a la productora cinematogr\u00e1fica y distribuidora estadounidense Warner Bros., que celebra este a\u00f1o su centenario y que se prolongar\u00e1 durante los pr\u00f3ximos tres meses.<\/p>\n<p>En concreto, se han programado este mes de agosto t\u00edtulos como \u2018El cantor de jazz\u2019, la pel\u00edcula que inaugur\u00f3 el cine sonoro, \u2018Bird\u2019, un espl\u00e9ndido biopic de Charlie Parker dirigido por Clint Eastwood, y \u2018Centauros del desierto\u2019, de John Ford, un cl\u00e1sico imperecedero.<\/p>\n<p>Asimismo, en agosto continuar\u00e1 el ciclo \u2018Fuera de foco. Premiadas\u2019, destinado a recuperar algunas de las pel\u00edculas m\u00e1s premiadas y m\u00e1s comentadas durante el \u00faltimo a\u00f1o.<\/p>\n<p>As\u00ed, se podr\u00e1n ver \u2018Todo a la vez en todas partes\u2019, la controvertida pel\u00edcula de Dan Kwan y Daniel Scheinert que triunf\u00f3 en la \u00faltima edici\u00f3n de los premios \u00d3scar, y \u2018Sinti\u00e9ndolo mucho\u2019, el documental sobre Joaqu\u00edn Sabina de Fernando Le\u00f3n de Aranoa que se llev\u00f3 el Goya a la mejor canci\u00f3n original.<\/p>\n<p>A estos largometrajes se sumar\u00e1 la estupenda \u2018Decision to leave\u2019, con la que Park Chan-wook se llev\u00f3 el premio a la mejor direcci\u00f3n en Cannes.<\/p>\n<p>Por otra parte, este mes prosigue el ciclo \u2018Por amor al cine\u2019 con la proyecci\u00f3n de la comedia screwball \u2018La fiera de mi ni\u00f1a\u2019, producida por la RKO en 1938 y con la m\u00e1gica dupla Cary Grant &#8211; Katharine Hepburn a las \u00f3rdenes de Howard Hawks.<\/p>\n<p>Este especial incluye tambi\u00e9n las proyecciones de otro filme protagonizado por Katharine Hepburn. Se trata de \u2018Locuras de verano\u2019, la \u00faltima pel\u00edcula firmada por David Lean en el Reino Unido antes de poner rumbo a los Estados Unidos para dirigir \u2018El puente sobre el r\u00edo Kwai\u2019.<\/p>\n<p>Dentro del ciclo In\u00e9ditos, la Filmoteca trae a Santander la pel\u00edcula argentina \u2018Trenque Lauquen\u2019, de Laura Citarella, una proyecci\u00f3n para valientes ya que duraci\u00f3n son 250 minutos, pero que merece la pena.<\/p>\n<p>Igualmente, CineInfinito presenta en agosto en la sala c\u00e1ntabra cuatro nuevos t\u00edtulos de su \u2018S\u00e8rie noire\u2019. Por un lado, dos de Paul Wendkos, que son \u2018The burglar\u2019 y \u2018The case against Brooklyn\u2019, y por otro, otros dos de Irving Lerner (\u201cMurder by contract\u201d y \u201cCity of fear\u201d).<\/p>\n<p>La colaboraci\u00f3n mensual con la asociaci\u00f3n La llave azul tiene prevista la proyecci\u00f3n los d\u00edas 17 y 18 de agosto de \u2018Secaderos\u2019, de Roc\u00edo Mesa, mientras que entre el 23 y el 27 de agosto la Filmoteca de Cantabria Mario Camus acoger\u00e1 las proyecciones de largometrajes del Picknic Festival.<\/p>\n<p>Adem\u00e1s, la Filmoteca Junior del mes de agosto incluye dos pel\u00edculas \u2018Lightyear\u2019, pel\u00edcula de animaci\u00f3n en clave de \u201cspace opera\u201d centrada en las aventuras de Buzz Lightyear, y \u2018Onward\u2019, una pel\u00edcula ambientada en un mundo fant\u00e1stico en la que dos hermanos elfos tratan de usar la magia para que su padre vuelva a la vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mes que viene contin\u00faan los ciclos \u2018Fuera de foco. Premiadas\u2019, \u2018Por amor al cine\u2019 y \u2018S\u00e8rie noire\u2019, junto a las habituales proyecciones de t\u00edtulos in\u00e9ditos y para p\u00fablico familiar Santander, 31 de julio de 2023.- La Filmoteca de Cantabria Mario Camus inicia en agosto un ciclo especial dedicado a la productora cinematogr\u00e1fica y distribuidora [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El mes que viene contin\u00faan los ciclos \u2018Fuera de foco. Premiadas\u2019, \u2018Por amor al cine\u2019 y \u2018S\u00e8rie noire\u2019, junto a las habituales proyecciones de t\u00edtulos in\u00e9ditos y para p\u00fablico familiar Santander, 31 de julio de 2023.- La Filmoteca de Cantabria Mario Camus inicia en agosto un ciclo especial dedicado a la productora cinematogr\u00e1fica y distribuidora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\" \/>\n<meta property=\"og:site_name\" content=\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-31T09:10:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2023\/07\/la-fiera-de-mi-nina-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"belen.cordoba@srecd.es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"belen.cordoba@srecd.es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\"},\"author\":{\"name\":\"belen.cordoba@srecd.es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8\"},\"headline\":\"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros.\",\"datePublished\":\"2023-07-31T09:10:38+00:00\",\"dateModified\":\"2023-07-31T09:10:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\"},\"wordCount\":550,\"publisher\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\",\"name\":\"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#website\"},\"datePublished\":\"2023-07-31T09:10:38+00:00\",\"dateModified\":\"2023-07-31T09:10:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/filmotecacantabria.es\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#website\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/\",\"name\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"description\":\"Toda la programaci\u00f3n de las filmotecas de Cantabria Mario Camus.\",\"publisher\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/filmotecacantabria.es\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\",\"name\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png\",\"contentUrl\":\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png\",\"width\":170,\"height\":183,\"caption\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\"},\"image\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8\",\"name\":\"belen.cordoba@srecd.es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g\",\"caption\":\"belen.cordoba@srecd.es\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/","og_locale":"es_ES","og_type":"article","og_title":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","og_description":"El mes que viene contin\u00faan los ciclos \u2018Fuera de foco. Premiadas\u2019, \u2018Por amor al cine\u2019 y \u2018S\u00e8rie noire\u2019, junto a las habituales proyecciones de t\u00edtulos in\u00e9ditos y para p\u00fablico familiar Santander, 31 de julio de 2023.- La Filmoteca de Cantabria Mario Camus inicia en agosto un ciclo especial dedicado a la productora cinematogr\u00e1fica y distribuidora [&hellip;]","og_url":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/","og_site_name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","article_published_time":"2023-07-31T09:10:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2023\/07\/la-fiera-de-mi-nina-3.jpg","type":"image\/jpeg"}],"author":"belen.cordoba@srecd.es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"belen.cordoba@srecd.es","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#article","isPartOf":{"@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/"},"author":{"name":"belen.cordoba@srecd.es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8"},"headline":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros.","datePublished":"2023-07-31T09:10:38+00:00","dateModified":"2023-07-31T09:10:38+00:00","mainEntityOfPage":{"@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/"},"wordCount":550,"publisher":{"@id":"https:\/\/filmotecacantabria.es\/es\/#organization"},"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/","url":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/","name":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros. - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","isPartOf":{"@id":"https:\/\/filmotecacantabria.es\/es\/#website"},"datePublished":"2023-07-31T09:10:38+00:00","dateModified":"2023-07-31T09:10:38+00:00","breadcrumb":{"@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/filmotecacantabria.es\/es\/iniciamos-en-agosto-un-ciclo-especial-para-conmemorar-el-centenario-de-la-warner-bros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/filmotecacantabria.es\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Iniciamos en agosto un ciclo especial para conmemorar el centenario de la Warner Bros."}]},{"@type":"WebSite","@id":"https:\/\/filmotecacantabria.es\/es\/#website","url":"https:\/\/filmotecacantabria.es\/es\/","name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","description":"Toda la programaci\u00f3n de las filmotecas de Cantabria Mario Camus.","publisher":{"@id":"https:\/\/filmotecacantabria.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filmotecacantabria.es\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/filmotecacantabria.es\/es\/#organization","name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","url":"https:\/\/filmotecacantabria.es\/es\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png","contentUrl":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png","width":170,"height":183,"caption":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n"},"image":{"@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8","name":"belen.cordoba@srecd.es","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g","caption":"belen.cordoba@srecd.es"}}]}},"_links":{"self":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3484"}],"collection":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/comments?post=3484"}],"version-history":[{"count":2,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3484\/revisions"}],"predecessor-version":[{"id":3487,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3484\/revisions\/3487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/media\/3485"}],"wp:attachment":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/media?parent=3484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/categories?post=3484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/tags?post=3484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}