{"id":3395,"date":"2023-05-24T10:00:47","date_gmt":"2023-05-24T08:00:47","guid":{"rendered":"https:\/\/filmotecacantabria.es\/es\/?p=3395"},"modified":"2023-05-24T10:09:24","modified_gmt":"2023-05-24T08:09:24","slug":"la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos","status":"publish","type":"post","link":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/","title":{"rendered":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos"},"content":{"rendered":"<p><strong>Los documentales grabados entre marzo y abril dan voz y visibilizan la historia de las amas de cr\u00eda, creando un relato construido por mujeres<\/strong><\/p>\n<p>Santander, 23 de mayo de 2023.- La Filmoteca de Cantabria Mario Camus ha acogido la proyecci\u00f3n de los cortometrajes elaborados en el taller colaborativo \u2018Las amas de cr\u00eda\u2019, desarrollado con la participaci\u00f3n de mujeres de los Valles Pasiegos.<\/p>\n<p>Dirigido por Aitor S\u00e1nchez Smith, los documentales grabados entre marzo y abril dan voz y visibilizan el papel y la historia de las amas de cr\u00eda creando un relato construido por mujeres.<\/p>\n<p>Todo ello a trav\u00e9s de encuentros intergeneracionales de mujeres relacionadas o interesadas en la historia de las amas de cr\u00eda, que han estado coordinados por Roc\u00edo Fern\u00e1ndez, educadora de Selaya, licenciada en Derecho en la Universidad de Cantabria y t\u00e9cnica superior en Integraci\u00f3n Social especializada en Igualdad de G\u00e9nero en la Universidad Europea Miguel de Cervantes.<\/p>\n<p>La proyecci\u00f3n de los cortometrajes ha contado con la asistencia del vicepresidente y consejero de Universidades, Igualdad, Cultura y Deporte, Pablo Zuloaga, que ha estado acompa\u00f1ado por la directora general de Acci\u00f3n Cultural, Gema Agudo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los documentales grabados entre marzo y abril dan voz y visibilizan la historia de las amas de cr\u00eda, creando un relato construido por mujeres Santander, 23 de mayo de 2023.- La Filmoteca de Cantabria Mario Camus ha acogido la proyecci\u00f3n de los cortometrajes elaborados en el taller colaborativo \u2018Las amas de cr\u00eda\u2019, desarrollado con la [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":3396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Los documentales grabados entre marzo y abril dan voz y visibilizan la historia de las amas de cr\u00eda, creando un relato construido por mujeres Santander, 23 de mayo de 2023.- La Filmoteca de Cantabria Mario Camus ha acogido la proyecci\u00f3n de los cortometrajes elaborados en el taller colaborativo \u2018Las amas de cr\u00eda\u2019, desarrollado con la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\" \/>\n<meta property=\"og:site_name\" content=\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-24T08:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T08:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2023\/05\/amas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"belen.cordoba@srecd.es\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"belen.cordoba@srecd.es\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\"},\"author\":{\"name\":\"belen.cordoba@srecd.es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8\"},\"headline\":\"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos\",\"datePublished\":\"2023-05-24T08:00:47+00:00\",\"dateModified\":\"2023-05-24T08:09:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\"},\"wordCount\":223,\"publisher\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\",\"name\":\"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#website\"},\"datePublished\":\"2023-05-24T08:00:47+00:00\",\"dateModified\":\"2023-05-24T08:09:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/filmotecacantabria.es\/es\/inicio\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#website\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/\",\"name\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"description\":\"Toda la programaci\u00f3n de las filmotecas de Cantabria Mario Camus.\",\"publisher\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/filmotecacantabria.es\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#organization\",\"name\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png\",\"contentUrl\":\"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png\",\"width\":170,\"height\":183,\"caption\":\"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n\"},\"image\":{\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8\",\"name\":\"belen.cordoba@srecd.es\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g\",\"caption\":\"belen.cordoba@srecd.es\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/","og_locale":"es_ES","og_type":"article","og_title":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","og_description":"Los documentales grabados entre marzo y abril dan voz y visibilizan la historia de las amas de cr\u00eda, creando un relato construido por mujeres Santander, 23 de mayo de 2023.- La Filmoteca de Cantabria Mario Camus ha acogido la proyecci\u00f3n de los cortometrajes elaborados en el taller colaborativo \u2018Las amas de cr\u00eda\u2019, desarrollado con la [&hellip;]","og_url":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/","og_site_name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","article_published_time":"2023-05-24T08:00:47+00:00","article_modified_time":"2023-05-24T08:09:24+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2023\/05\/amas.jpg","type":"image\/jpeg"}],"author":"belen.cordoba@srecd.es","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"belen.cordoba@srecd.es","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#article","isPartOf":{"@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/"},"author":{"name":"belen.cordoba@srecd.es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8"},"headline":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos","datePublished":"2023-05-24T08:00:47+00:00","dateModified":"2023-05-24T08:09:24+00:00","mainEntityOfPage":{"@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/"},"wordCount":223,"publisher":{"@id":"https:\/\/filmotecacantabria.es\/es\/#organization"},"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/","url":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/","name":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos - Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","isPartOf":{"@id":"https:\/\/filmotecacantabria.es\/es\/#website"},"datePublished":"2023-05-24T08:00:47+00:00","dateModified":"2023-05-24T08:09:24+00:00","breadcrumb":{"@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/filmotecacantabria.es\/es\/la-filmoteca-de-cantabria-proyecta-los-cortometrajes-del-taller-colaborativo-sobre-las-amas-de-cria-realizado-por-mujeres-de-los-valles-pasiegos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/filmotecacantabria.es\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"La Filmoteca de Cantabria proyecta los cortometrajes del taller colaborativo sobre \u2018Las amas de cr\u00eda\u2019 realizado por mujeres de los Valles Pasiegos"}]},{"@type":"WebSite","@id":"https:\/\/filmotecacantabria.es\/es\/#website","url":"https:\/\/filmotecacantabria.es\/es\/","name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","description":"Toda la programaci\u00f3n de las filmotecas de Cantabria Mario Camus.","publisher":{"@id":"https:\/\/filmotecacantabria.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/filmotecacantabria.es\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/filmotecacantabria.es\/es\/#organization","name":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n","url":"https:\/\/filmotecacantabria.es\/es\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png","contentUrl":"https:\/\/filmotecacantabria.es\/es\/wp-content\/uploads\/2021\/12\/logo-filmoteca-cantabria-1-mario-camus.png","width":170,"height":183,"caption":"Filmoteca de Cantabria Mario Camus | Santander | Torrelavega | Regi\u00f3n"},"image":{"@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/86205b2ac543405aae888afb3afdb6d8","name":"belen.cordoba@srecd.es","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/filmotecacantabria.es\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a185108474f14fc94f32f86115d60aeb?s=96&d=mm&r=g","caption":"belen.cordoba@srecd.es"}}]}},"_links":{"self":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3395"}],"collection":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/comments?post=3395"}],"version-history":[{"count":1,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3395\/revisions"}],"predecessor-version":[{"id":3397,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/posts\/3395\/revisions\/3397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/media\/3396"}],"wp:attachment":[{"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/media?parent=3395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/categories?post=3395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filmotecacantabria.es\/es\/wp-json\/wp\/v2\/tags?post=3395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}